
{"id":1763,"date":"2022-03-09T07:36:00","date_gmt":"2022-03-09T07:36:00","guid":{"rendered":"https:\/\/overline-poetry.de\/?p=1763"},"modified":"2025-09-24T07:45:14","modified_gmt":"2025-09-24T07:45:14","slug":"putin-und-die-leeren-gasspeicher","status":"publish","type":"post","link":"https:\/\/overline-poetry.de\/index.php\/2022\/03\/09\/putin-und-die-leeren-gasspeicher\/","title":{"rendered":"Putin und die leeren Gasspeicher"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wie konnte es dem \u201ealten\u201c Wirtschaftsminister, Peter Altmeier, nur passieren,<br>dass er verga\u00df, regelm\u00e4\u00dfig den F\u00fcllzustand der Gasspeicher zu kontrollieren.<br>Vielleicht war es schon von Putin die Planung oder auch ein strategischer Zug,<br><strong>(Gesamt Text = 24 Zeilen)<br><a href=\"https:\/\/overline-poetry.de\/index.php\/putin-und-die-leeren-gasspeicher\/\" data-type=\"link\" data-id=\"https:\/\/overline-poetry.de\/index.php\/putin-und-die-leeren-gasspeicher\/\">Weiterlesen \/ read more<\/a> &#8211; 09.03.2022<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie konnte es dem \u201ealten\u201c Wirtschaftsminister, Peter Altmeier, nur passieren,dass er verga\u00df, regelm\u00e4\u00dfig den F\u00fcllzustand der Gasspeicher zu kontrollieren.Vielleicht war es schon von Putin die Planung oder auch ein strategischer Zug,(Gesamt Text = 24 Zeilen)Weiterlesen \/ read more &#8211; 09.03.2022<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,176,45,271,5],"tags":[337,633,187,632,190,634],"class_list":["post-1763","post","type-post","status-publish","format-standard","hentry","category-cdu-csu","category-personen","category-putin","category-russland","category-satire","tag-altkanzler-schroeder","tag-altmeier","tag-angriffskrieg","tag-gasspeicher","tag-ukraine","tag-wirtschaftsminister"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts\/1763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/comments?post=1763"}],"version-history":[{"count":1,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts\/1763\/revisions"}],"predecessor-version":[{"id":1764,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts\/1763\/revisions\/1764"}],"wp:attachment":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/media?parent=1763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/categories?post=1763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/tags?post=1763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}