
{"id":2274,"date":"2025-12-19T10:13:14","date_gmt":"2025-12-19T10:13:14","guid":{"rendered":"https:\/\/overline-poetry.de\/?p=2274"},"modified":"2025-12-21T16:05:23","modified_gmt":"2025-12-21T16:05:23","slug":"putin-und-seine-weihnachts-luegerede","status":"publish","type":"post","link":"https:\/\/overline-poetry.de\/index.php\/2025\/12\/19\/putin-und-seine-weihnachts-luegerede\/","title":{"rendered":"Putin und seine Weihnachts-L\u00fcgen(Rede)"},"content":{"rendered":"\n<p>Eine Nutzung der eingefrorenen <strong>Russland-Milliarden<\/strong>, das w\u00e4re Raub,<br>aber was <strong>Putin<\/strong> mit der <strong>Ukraine<\/strong> macht, auf dem Ohr, scheint er \u201etaub\u201c.<br><strong>Putin<\/strong> bel\u00fcgt sein Volk, er musste die <strong>Ukraine<\/strong> vor Nazis besch\u00fctzen,<br><strong>(Gesamt Text = 28 Zeilen)<br><a href=\"https:\/\/overline-poetry.de\/index.php\/putin-und-seine-weihnachts-luegerede\/\" data-type=\"link\" data-id=\"https:\/\/overline-poetry.de\/index.php\/putin-und-seine-weihnachts-luegerede\/\">Weiterlesen \/ read more<\/a> &#8211; 19.12.2025<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Nutzung der eingefrorenen Russland-Milliarden, das w\u00e4re Raub,aber was Putin mit der Ukraine macht, auf dem Ohr, scheint er \u201etaub\u201c.Putin bel\u00fcgt sein Volk, er musste die Ukraine vor Nazis besch\u00fctzen,(Gesamt Text = 28 Zeilen)Weiterlesen \/ read more &#8211; 19.12.2025<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,309,8,45,271,5,245],"tags":[209,775,275,46,774,249,190],"class_list":["post-2274","post","type-post","status-publish","format-standard","hentry","category-nachdenkliches","category-nato","category-politik","category-putin","category-russland","category-satire","category-ukraine","tag-despot-putin","tag-eingefrorenes-russisches-vermoegen","tag-eu","tag-putin","tag-russische-milliarden","tag-russland","tag-ukraine"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts\/2274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/comments?post=2274"}],"version-history":[{"count":2,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts\/2274\/revisions"}],"predecessor-version":[{"id":2280,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts\/2274\/revisions\/2280"}],"wp:attachment":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/media?parent=2274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/categories?post=2274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/tags?post=2274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}