
{"id":775,"count":1,"description":"","link":"https:\/\/overline-poetry.de\/index.php\/tag\/eingefrorenes-russisches-vermoegen\/","name":"eingefrorenes russisches Verm\u00f6gen","slug":"eingefrorenes-russisches-vermoegen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/tags\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/overline-poetry.de\/index.php\/wp-json\/wp\/v2\/posts?tags=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}